{"id":88,"count":1,"description":"","link":"https:\/\/www.luzukdemo.com\/demo\/food-recipe\/category\/aciform\/","name":"aciform","slug":"aciform","taxonomy":"category","parent":0,"meta":[],"z_taxonomy_image_url":"https:\/\/www.luzukdemo.com\/demo\/food-recipe\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","_links":{"self":[{"href":"https:\/\/www.luzukdemo.com\/demo\/food-recipe\/wp-json\/wp\/v2\/categories\/88","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.luzukdemo.com\/demo\/food-recipe\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.luzukdemo.com\/demo\/food-recipe\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.luzukdemo.com\/demo\/food-recipe\/wp-json\/wp\/v2\/posts?categories=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}